{"id":3381,"date":"2020-09-22T01:06:25","date_gmt":"2020-09-22T06:06:25","guid":{"rendered":"https:\/\/lima.wordcamp.org\/2020\/?post_type=wcb_sponsor&#038;p=3381"},"modified":"2020-09-23T20:42:30","modified_gmt":"2020-09-24T01:42:30","slug":"wohuk","status":"publish","type":"wcb_sponsor","link":"https:\/\/lima.wordcamp.org\/2020\/sponsor\/wohuk\/","title":{"rendered":"WOHUK"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">2006 iniciamos a desarrollar themes y plugins para WordPress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2012 tuvimos nuestro primer proyecto con WooCommerce, desde ah\u00ed no paramos desarrollando soluciones con WooCommerce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2020 decidimos registrarnos como una marca especializada en brindar soluciones para WooCommerce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2006 iniciamos a desarrollar themes y plugins para WordPress. 2012 tuvimos nuestro primer proyecto con WooCommerce, desde ah\u00ed no paramos desarrollando soluciones con WooCommerce. 2020 decidimos registrarnos como una marca especializada en brindar soluciones para WooCommerce.<\/p>\n","protected":false},"featured_media":3386,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"https:\/\/wohuk.com\/","footnotes":""},"sponsor_level":[23],"class_list":["post-3381","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-startup"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sponsors\/3381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sponsors\/3381\/revisions"}],"predecessor-version":[{"id":3382,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sponsors\/3381\/revisions\/3382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/media\/3386"}],"wp:attachment":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/media?parent=3381"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sponsor_level?post=3381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}