{"id":1989,"date":"2020-07-13T21:20:52","date_gmt":"2020-07-14T02:20:52","guid":{"rendered":"https:\/\/2020.lima.wordcamp.org\/?post_type=wcb_session&#038;p=1989"},"modified":"2020-09-18T01:54:14","modified_gmt":"2020-09-18T06:54:14","slug":"cuanto-cuesta-un-sitio-web-estrategias-para-la-fijacion-de-precios","status":"publish","type":"wcb_session","link":"https:\/\/lima.wordcamp.org\/2020\/session\/cuanto-cuesta-un-sitio-web-estrategias-para-la-fijacion-de-precios\/","title":{"rendered":"\u00bfCu\u00e1nto cuesta un sitio web? &#8211; Estrategias para la fijaci\u00f3n de precios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u00bfSabes cotizar correctamente la construcci\u00f3n de un sitio web? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta charla nuestro ponente, Leandro G\u00f3mez (Uruguay), nos ense\u00f1ar\u00e1 c\u00f3mo desarrollar una estrategia de fijaci\u00f3n de precios y calcular tus costos para que tu negocio o emprendimiento sea rentable. Conoce las variables que influyen en el costo final de un proyecto con ejemplos pr\u00e1cticos y sencillos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/lima.wordcamp.org\/2020\/files\/2020\/09\/9.png\" alt=\"\" class=\"wp-image-3109\" srcset=\"https:\/\/lima.wordcamp.org\/2020\/files\/2020\/09\/9.png 940w, https:\/\/lima.wordcamp.org\/2020\/files\/2020\/09\/9-300x251.png 300w, https:\/\/lima.wordcamp.org\/2020\/files\/2020\/09\/9-768x644.png 768w, https:\/\/lima.wordcamp.org\/2020\/files\/2020\/09\/9-358x300.png 358w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSabes cotizar correctamente la construcci\u00f3n de un sitio web? En esta charla nuestro ponente, Leandro G\u00f3mez (Uruguay), nos ense\u00f1ar\u00e1 c\u00f3mo desarrollar una estrategia de fijaci\u00f3n de precios y calcular tus costos para que tu negocio o emprendimiento sea rentable. Conoce las variables que influyen en el costo final de un proyecto con ejemplos pr\u00e1cticos y &hellip; <a href=\"https:\/\/lima.wordcamp.org\/2020\/session\/cuanto-cuesta-un-sitio-web-estrategias-para-la-fijacion-de-precios\/\" class=\"more-link\">Sigue leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfCu\u00e1nto cuesta un sitio web? &#8211; Estrategias para la fijaci\u00f3n de precios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":10987929,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1601073000,"_wcpt_session_duration":2700,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[2278],"footnotes":""},"session_track":[19],"session_category":[],"class_list":["post-1989","wcb_session","type-wcb_session","status-publish","hentry","wcb_track-sala-b"],"jetpack_sharing_enabled":true,"session_date_time":{"date":"septiembre 25, 2020","time":"5:30 PM"},"session_speakers":[{"id":"2278","slug":"leandro-gomez","name":"Leandro G\u00f3mez","link":"https:\/\/lima.wordcamp.org\/2020\/speaker\/leandro-gomez\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sessions\/1989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/types\/wcb_session"}],"version-history":[{"count":4,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sessions\/1989\/revisions"}],"predecessor-version":[{"id":3110,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/sessions\/1989\/revisions\/3110"}],"speakers":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/speakers\/2278"}],"author":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wporg\/v1\/users\/leogg"}],"wp:attachment":[{"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/media?parent=1989"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/session_track?post=1989"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2020\/wp-json\/wp\/v2\/session_category?post=1989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}