{"id":631,"date":"2016-07-16T02:39:07","date_gmt":"2016-07-16T07:39:07","guid":{"rendered":"https:\/\/2016.lima.wordcamp.org\/?post_type=wcb_sponsor&#038;p=631"},"modified":"2016-07-16T02:39:07","modified_gmt":"2016-07-16T07:39:07","slug":"beeznest","status":"publish","type":"wcb_sponsor","link":"https:\/\/lima.wordcamp.org\/2016\/sponsor\/beeznest\/","title":{"rendered":"BeezNest"},"content":{"rendered":"<p>BeezNest es una compa\u00f1\u00eda de consultor\u00eda en tecnolog\u00edas de la informaci\u00f3n\u00a0y desarrollo de software, fundada en 2002 con las mejores pr\u00e1cticas de\u00a0E-learning e Infraestructura de alto desempe\u00f1o en la nube para la\u00a0implementaci\u00f3n de proyectos a gran escala.<\/p>\n<p>Trabajamos desde nuestras sedes en B\u00e9lgica, Espa\u00f1a, Francia y Lima,\u00a0Per\u00fa, con las tecnolog\u00edas Open Source m\u00e1s eficientes del mercado\u00a0(Chamilo LMS, Drupal, WordPress, ERP, etc). Por eso apoyamos el software\u00a0libre y destinamos el 25% de nuestros beneficios anuales a Chamilo LMS y\u00a0otros proyectos de software libre, tanto en tiempo de desarrollo como\u00a0para nuevas funcionalidades y donaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BeezNest es una compa\u00f1\u00eda de consultor\u00eda en tecnolog\u00edas de la informaci\u00f3n\u00a0y desarrollo de software, fundada en 2002 con las mejores pr\u00e1cticas de\u00a0E-learning e Infraestructura de alto desempe\u00f1o en la nube para la\u00a0implementaci\u00f3n de proyectos a gran escala. Trabajamos desde nuestras &hellip; <a href=\"https:\/\/lima.wordcamp.org\/2016\/sponsor\/beeznest\/\">Sigue leyendo <span class=\"assistive-text\">BeezNest<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":632,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"https:\/\/beeznest.com\/es\/","footnotes":""},"sponsor_level":[11517],"class_list":["post-631","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-startup"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7dLI2-ab","_links":{"self":[{"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/631\/revisions"}],"predecessor-version":[{"id":633,"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsors\/631\/revisions\/633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/media\/632"}],"wp:attachment":[{"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/media?parent=631"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2016\/wp-json\/wp\/v2\/sponsor_level?post=631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}