{"id":12048,"date":"2013-10-19T11:00:08","date_gmt":"2013-10-19T16:00:08","guid":{"rendered":"https:\/\/2013.lima.wordcamp.org\/?post_type=wcb_session&#038;p=12048"},"modified":"2013-10-20T19:31:04","modified_gmt":"2013-10-21T00:31:04","slug":"conociendo-wordpress","status":"publish","type":"wcb_session","link":"https:\/\/lima.wordcamp.org\/2013\/session\/conociendo-wordpress\/","title":{"rendered":"Conociendo WordPress"},"content":{"rendered":"<p>Para empezar viendo WorPress, primero aprenderemos acerca de los que es un gestor de contenidos (CMS) y para qu\u00e9 sirve. Lo b\u00e1sico de WordPress y la personalizaci\u00f3n del sistema para que aprovechemos los recursos que nos brinda. Para hacer una web s\u00f3lo es necesario querer hacerla, WordPress har\u00e1 el resto.<\/p>\n<p style=\"text-align:center\">&#8211; Paola Arca &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para empezar viendo WorPress, primero aprenderemos acerca de los que es un gestor de contenidos (CMS) y para qu\u00e9 sirve. Lo b\u00e1sico de WordPress y la personalizaci\u00f3n del sistema para que aprovechemos los recursos que nos brinda. Para hacer una &hellip; <a href=\"https:\/\/lima.wordcamp.org\/2013\/session\/conociendo-wordpress\/\">Sigue leyendo <span class=\"screen-reader-text\">Conociendo WordPress<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5305144,"featured_media":0,"template":"","meta":{"_crdt_document":"","_wcpt_session_time":1382198400,"_wcpt_session_duration":3000,"_wcpt_session_type":"session","_wcpt_session_slides":"","_wcpt_session_video":"","_wcpt_speaker_id":[12046],"footnotes":""},"session_track":[],"session_category":[],"class_list":["post-12048","wcb_session","type-wcb_session","status-publish","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/pheVtk-38k","jetpack_sharing_enabled":true,"session_date_time":{"date":"octubre 19, 2013","time":"11:00 am"},"session_speakers":[{"id":"12046","slug":"paola-arca","name":"Paola Arca","link":"https:\/\/lima.wordcamp.org\/2013\/speaker\/paola-arca\/"}],"session_cats_rendered":null,"_links":{"self":[{"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/sessions\/12048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/sessions"}],"about":[{"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/types\/wcb_session"}],"author":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/users\/5305144"}],"version-history":[{"count":8,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/sessions\/12048\/revisions"}],"predecessor-version":[{"id":16747,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/sessions\/12048\/revisions\/16747"}],"speakers":[{"embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/speakers\/12046"}],"wp:attachment":[{"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/media?parent=12048"}],"wp:term":[{"taxonomy":"wcb_track","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/session_track?post=12048"},{"taxonomy":"wcb_session_category","embeddable":true,"href":"https:\/\/lima.wordcamp.org\/2013\/wp-json\/wp\/v2\/session_category?post=12048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}